{"id":10547,"date":"2011-08-11T01:27:02","date_gmt":"2011-08-11T00:27:02","guid":{"rendered":"http:\/\/best-of-high-tech.com\/fr\/?p=10547"},"modified":"2011-08-11T01:27:02","modified_gmt":"2011-08-11T00:27:02","slug":"modele-lettre-motivation-responsable-achats","status":"publish","type":"post","link":"https:\/\/best-of-high-tech.com\/fr\/modele-lettre-motivation-responsable-achats\/","title":{"rendered":"modele de lettre de motivation responsable des achats \u2013 exemple gratuit"},"content":{"rendered":"<p style=\"text-align: justify; \">\n\t<strong>Un exemple de lettre de motivation&nbsp;<\/strong><strong>pour une reponse a une offre de poste de<\/strong><strong>&nbsp;responsable des achats&nbsp;:<\/strong><\/p>\n<p style=\"margin-left: 40px; \">\n\t<span style=\"font-size: 14px; \"><strong>Votre Pr&eacute;nom NOM<\/strong><\/span><br \/>\n\tVotre adresse compl&egrave;te<br \/>\n\tT&eacute;l&eacute;phone \/ Email&#8230;<\/p>\n<p style=\"margin-left: 360px; \">\n\t<strong><span style=\"font-size: 14px; \">NOM DE LA SOCIETE<\/span><\/strong><br \/>\n\tAdresse de la soci&eacute;t&eacute;<\/p>\n<p style=\"margin-left: 360px; \">\n\tParis, <strong>Date<\/strong><\/p>\n<p style=\"margin-left: 200px; \">\n\t<strong>Madame, Monsieur,<\/strong><\/p>\n<p>\n\t&nbsp;<\/p>\n<p style=\"text-align: justify; margin-left: 40px; \">\n\tL&#39;annonce que vous avez fait para&icirc;tre sous la r&eacute;f&eacute;rence XXXX a tout particuli&egrave;rement retenu mon attention. En effet le poste de responsable achats &agrave; pourvoir, correspond tr&egrave;s exactement &agrave; mon exp&eacute;rience et &agrave; mes aspirations professionnelles.<\/p>\n<p style=\"text-align: justify; margin-left: 40px; \">\n\tLes secteurs dans lesquels j&#39;ai &eacute;volu&eacute; &eacute;taient dynamiques et m&#39;ont permis de d&eacute;velopper mon sens des responsabilit&eacute;s et d&#39;accro&icirc;tre mes capacit&eacute;s d&#39;adaptation. Chez XXXX en qualit&eacute; de responsable achats, j&#39;ai assur&eacute; la gestion, l&#39;organisation et le contr&ocirc;le interne des achats de prestations de biens et anim&eacute; une &eacute;quipe de 5 personnes. Chez YYYY j&#39;ai &eacute;t&eacute; en charge de la gestion du portefeuille des frais g&eacute;n&eacute;raux.&nbsp;<\/p>\n<p style=\"text-align: justify; margin-left: 40px; \">\n\tJ&#39;ai pu ainsi acqu&eacute;rir ces derni&egrave;res ann&eacute;es une certaine autonomie ainsi que la rigueur indispensable &agrave; ce poste. Vivement int&eacute;ress&eacute;e par cette fonction, je souhaiterais vous exposer plus en d&eacute;tail ma motivation lors d&#39;un prochain entretien.&nbsp;<\/p>\n<p style=\"text-align: justify; margin-left: 40px; \">\n\tDans cette attente, veuillez agr&eacute;er, Monsieur, l&#39;expression de mes sinc&egrave;res salutations.<\/p>\n<p style=\"text-align: justify; margin-left: 40px; \">\n\t&nbsp;<\/p>\n<p style=\"text-align: justify; margin-left: 520px; \">\n\t<span class=\"Apple-style-span\" style=\"font-weight: bold; \">Ma Signature<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un exemple de lettre de motivation pour une reponse a une offre de poste de responsable des achats :<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[93],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/posts\/10547"}],"collection":[{"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/comments?post=10547"}],"version-history":[{"count":3,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/posts\/10547\/revisions"}],"predecessor-version":[{"id":11151,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/posts\/10547\/revisions\/11151"}],"wp:attachment":[{"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/media?parent=10547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/categories?post=10547"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/tags?post=10547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}