{"id":10801,"date":"2011-08-11T00:48:02","date_gmt":"2011-08-10T23:48:02","guid":{"rendered":"http:\/\/best-of-high-tech.com\/fr\/?p=10801"},"modified":"2011-08-11T00:48:02","modified_gmt":"2011-08-10T23:48:02","slug":"lettre-de-motivation-architecte-dinterieur-%e2%80%93-exemple-gratuit-modele","status":"publish","type":"post","link":"https:\/\/best-of-high-tech.com\/fr\/lettre-de-motivation-architecte-dinterieur-%e2%80%93-exemple-gratuit-modele\/","title":{"rendered":"lettre de motivation: Architecte d&rsquo;int\u00e9rieur \u2013 exemple gratuit, mod\u00e8le"},"content":{"rendered":"<p style=\"text-align: justify; \">\n\t<strong>Un exemple de lettre de motivation pour un poste d&#39;Architecte d&#39;int&eacute;rieur &nbsp;:<\/strong><\/p>\n<p style=\"margin-left: 40px; \">\n\t<span style=\"font-size: 14px; \"><strong>Votre Pr&eacute;nom NOM<\/strong><\/span><br \/>\n\tVotre adresse compl&egrave;te<br \/>\n\tT&eacute;l&eacute;phone \/ Email&#8230;<\/p>\n<p style=\"margin-left: 360px; \">\n\t<strong><span style=\"font-size: 14px; \">NOM DE LA SOCIETE<\/span><\/strong><br \/>\n\tAdresse de la soci&eacute;t&eacute;<\/p>\n<p style=\"margin-left: 360px; \">\n\tParis, <strong>Date<\/strong><\/p>\n<p style=\"margin-left: 200px; \">\n\t<strong>Madame, Monsieur,<\/strong><\/p>\n<p>\n\t&nbsp;<\/p>\n<p style=\"margin-left: 40px; text-align: justify; \">\n\tArchitecte d&rsquo;int&eacute;rieur dipl&ocirc;m&eacute;e de l&rsquo;&eacute;cole sup&eacute;rieure d&rsquo;arts appliqu&eacute;s Boulle, je postule pour le poste r&eacute;f&eacute;renc&eacute; ci-dessus.<\/p>\n<p style=\"margin-left: 40px; text-align: justify; \">\n\tEn effet, d&eacute;sireuse de donner un nouvel &eacute;lan &agrave; ma carri&egrave;re, je souhaite aujourd&rsquo;hui m&rsquo;associer &agrave; un projet tel que le v&ocirc;tre. Travailler dans un cabinet d&rsquo;&eacute;tude a toujours &eacute;t&eacute; mon objectif premier, je saisis donc l&rsquo;occasion qui m&rsquo;en est donn&eacute;e.<\/p>\n<p style=\"margin-left: 40px; text-align: justify; \">\n\tL&rsquo;agencement d&rsquo;un appartement n&rsquo;a plus de secret pour moi. Je poss&egrave;de de bonnes connaissances en mobilier et design, ainsi qu&rsquo;en CAO et DAO. J&rsquo;ai une grande sensibilit&eacute; artistique (je suis peintre amateur) et le sens du contact avec la client&egrave;le et les diff&eacute;rents intervenants dans la r&eacute;alisation d&rsquo;un projet.<\/p>\n<p style=\"margin-left: 40px; text-align: justify; \">\n\tConcevoir un lieu fonctionnel, trouver des solutions qui soient &agrave; la fois pratiques et esth&eacute;tiques est pour moi une passion. Jouer avec les volumes, les mat&eacute;riaux, les couleurs me permet d&rsquo;exprimer pleinement ma cr&eacute;ativit&eacute;.<\/p>\n<p style=\"margin-left: 40px; text-align: justify; \">\n\tJe ma&icirc;trise &eacute;galement parfaitement l&rsquo;aspect technique : montage du dossier et suivi du chantier, toujours dans le respect du cahier des charges et des d&eacute;lais.<\/p>\n<p style=\"margin-left: 40px; text-align: justify; \">\n\tSi vous d&eacute;sirez en savoir davantage, je me tiens &agrave; votre disposition pour un entretien et vous prie de recevoir, Madame, Monsieur, mes sinc&egrave;res salutations.<\/p>\n<p style=\"margin-left: 40px; text-align: justify; \">\n\t&nbsp;<\/p>\n<p style=\"text-align: justify; margin-left: 520px; \">\n\t<span class=\"Apple-style-span\" style=\"font-weight: bold; \">Ma Signature<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un exemple de lettre de motivation pour un poste d&rsquo;Architecte d&rsquo;int\u00e9rieur  :<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[93],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/posts\/10801"}],"collection":[{"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/comments?post=10801"}],"version-history":[{"count":4,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/posts\/10801\/revisions"}],"predecessor-version":[{"id":11051,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/posts\/10801\/revisions\/11051"}],"wp:attachment":[{"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/media?parent=10801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/categories?post=10801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/tags?post=10801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}