{"id":11707,"date":"2011-10-05T00:12:08","date_gmt":"2011-10-04T23:12:08","guid":{"rendered":"http:\/\/best-of-high-tech.com\/fr\/?p=11707"},"modified":"2011-10-05T00:12:08","modified_gmt":"2011-10-04T23:12:08","slug":"modele-lettre-offre-achat-immobilier","status":"publish","type":"post","link":"https:\/\/best-of-high-tech.com\/fr\/modele-lettre-offre-achat-immobilier\/","title":{"rendered":"modele de lettre d&rsquo;offre d&rsquo;achat immobilier &#8211; exemple type gratuit"},"content":{"rendered":"<p>\n\tVous souhaitez acheter l&rsquo;appartement de vos r&ecirc;ves. Le prix propos&eacute; par le vendeur ne vous convenant pas, vous souhaitez faire une offre d&rsquo;achat.<\/p>\n<div style=\"margin-left: 32px; text-align: justify; margin-right: 40px; border: 1px solid #CCC; padding-right: 10px; padding-left: 10px;\">\n<p>\n\t\t&nbsp;<\/p>\n<p>\n\t\tLe(s) proposant(s)<\/p>\n<p>\n\t\t&nbsp;<\/p>\n<p>\n\t\tJe soussign&eacute; ________________ (<span style=\"color:#800080;\">nom et pr&eacute;nom<\/span>), __________________ (<span style=\"color:#800080;\">profession de l&rsquo;offrant)<\/span>, r&eacute;sidant actuellement __________________ (adresse actuelle de l&rsquo;offrant), n&eacute;(e) le __________ (<span style=\"color:#800080;\">date<\/span>) &agrave; ___________ (<span style=\"color:#800080;\">ville<\/span>), de nationalit&eacute; ___________ <span style=\"color:#800080;\">(nationalit&eacute;<\/span>), ________________ (<span style=\"color:#800080;\">situation personnelle : c&eacute;libataire, mari&eacute; sous le r&eacute;gime de la communaut&eacute; de biens, mari&eacute; sous le r&eacute;gime de la s&eacute;paration de biens, pacs&eacute;&hellip;<\/span>)<\/p>\n<p>\n\t\t&nbsp;<\/p>\n<p>\n\t\t(si plusieurs offrants, comme par exemple le mari et la femme)<\/p>\n<p>\n\t\tEt<\/p>\n<p>\n\t\tJe soussign&eacute; ________________ (<span style=\"color:#800080;\">nom et pr&eacute;nom<\/span>), __________________ <span style=\"color:#800080;\">(profession de l&rsquo;offrant<\/span>), r&eacute;sidant actuellement __________________ (<span style=\"color:#800080;\">adresse actuelle de l&rsquo;offrant<\/span>), n&eacute;(e) le __________ (<span style=\"color:#800080;\">date<\/span>) &agrave; ___________ <span style=\"color:#800080;\">(ville),<\/span> de nationalit&eacute; ___________ <span style=\"color:#800080;\">(nationalit&eacute;),<\/span> ________________<span style=\"color:#800080;\"> (situation personnelle : c&eacute;libataire, mari&eacute; sous le r&eacute;gime de la communaut&eacute; de biens, mari&eacute; sous le r&eacute;gime de la s&eacute;paration de biens, pacs&eacute;&hellip;)<\/span><\/p>\n<p>\n\t\t&nbsp;<\/p>\n<p>\n\t\tEtant pr&eacute;cis&eacute; que, si plusieurs proposants interviennent, ceux-ci agiront conjointement et solidairement entre eux et d&eacute;clarent que rien dans leur &eacute;tat civil respectif, ni dans leur capacit&eacute;, ne constitue un obstacle ou un emp&ecirc;chement &agrave; la validit&eacute; de la pr&eacute;sente proposition d&rsquo;achat.&nbsp;<\/p>\n<p>\n\t\t&nbsp;<\/p>\n<p>\n\t\tReconna&icirc;t\/reconnaissons avoir, gr&acirc;ce &agrave; votre intervention, visit&eacute; le bien d&eacute;sign&eacute; ci-apr&egrave;s, le ___________________ <span style=\"color:#800080;\">(date de la visite)<\/span>.<\/p>\n<p>\n\t\t&nbsp;<\/p>\n<p>\n\t\t<strong>D&eacute;signation du bien :<\/strong><\/p>\n<p style=\"margin-left: 40px; \">\n\t\tType de bien <span style=\"color:#800080;\">(maison, appartement, nombre de pi&egrave;ces)<\/span> : ____________<\/p>\n<p style=\"margin-left: 40px; \">\n\t\tCommune et adresse : __________________<\/p>\n<p style=\"margin-left: 40px; \">\n\t\tSurface : ______________<\/p>\n<p style=\"margin-left: 40px; \">\n\t\tSurface du terrain : __________<span class=\"Apple-tab-span\" style=\"white-space:pre\"> <\/span><\/p>\n<p style=\"margin-left: 40px; \">\n\t\tSituation d&rsquo;occupation <span style=\"color:#800080;\">(libre \/ lou&eacute;)<\/span> : ____________<\/p>\n<p style=\"margin-left: 40px; \">\n\t\tBien port&eacute; au registre des mandats sous le n&deg; ____________<span style=\"color:#800080;\"> (uniquement si une agence est charg&eacute;e de vendre le bien)<\/span><\/p>\n<p>\n\t\t&nbsp;<\/p>\n<p>\n\t\tSuite &agrave; cette visite, je\/Nous d&eacute;clare\/d&eacute;clarons conna&icirc;tre la consistance et les caract&eacute;ristiques et propose\/proposons de l&rsquo;acheter aux conditions suivantes :<\/p>\n<p>\n\t\t<strong>Prix propos&eacute; :<\/strong><\/p>\n<p>\n\t\tSous r&eacute;serve de l&rsquo;acceptation du propri&eacute;taire, ma\/notre proposition est faite au prix de ________ euros <span style=\"color:#800080;\">(somme en chiffres et en toutes lettres) <\/span>qui sera pay&eacute; int&eacute;gralement le jour de l&rsquo;acte authentique de vente.<\/p>\n<p>\n\t\tLa vente aura lieu sous conditions ordinaires et de droit en pareille mati&egrave;re. Le transfert de propri&eacute;t&eacute; aura lieu le jour de la r&eacute;it&eacute;ration de la vente par acte authentique.<\/p>\n<p>\n\t\t<strong>Financement de l&rsquo;acquisition :<\/strong><\/p>\n<p>\n\t\tLes modalit&eacute;s de financement seront d&eacute;termin&eacute;es aux termes de l&rsquo;avant-contrat.<\/p>\n<p>\n\t\tSi vous envisagez de financer le bien par un cr&eacute;dit immobilier, indiquez les &eacute;l&eacute;ments fournis par votre banque :<\/p>\n<p>\n\t\tL&rsquo;acquisition sera financ&eacute;e par un cr&eacute;dit bancaire au taux de _____________________<span style=\"color:#800080;\"> (indiquez le taux d&rsquo;int&eacute;r&ecirc;t envisag&eacute;)<\/span> remboursable sur une dur&eacute;e de _________ ans<span style=\"color:#800080;\"> (indiquez la dur&eacute;e de remboursement envisag&eacute;e).<\/span><\/p>\n<p>\n\t\t<strong>Conditions de l&rsquo;offre :<\/strong><\/p>\n<p>\n\t\tL&rsquo;offre est faite pour une dur&eacute;e de ________ jours, &agrave; compter du ___________ <span style=\"color:#800080;\">(date de signature de l&rsquo;offre).<\/span><\/p>\n<p>\n\t\tL&rsquo;acceptation du vendeur devra &ecirc;tre port&eacute;e sur le pr&eacute;sent acte avant la date fix&eacute;e.&nbsp;<\/p>\n<p>\n\t\tL&rsquo;acceptation de l&rsquo;offre par le b&eacute;n&eacute;ficiaire rendra la vente parfaite, conform&eacute;ment aux dispositions de l&rsquo;article 1583 du code civil, les parties &eacute;tant d&rsquo;accord sur la chose et sur le prix. Cet accord sera imm&eacute;diatement constat&eacute; par un compromis de vente.<\/p>\n<p>\n\t\tEn l&rsquo;absence d&rsquo;acceptation de la pr&eacute;sente offre, celle-ci s&rsquo;&eacute;teindra le _____________ <span style=\"color:#800080;\">(date)<\/span>, &agrave; minuit.<\/p>\n<p>\n\t\t<strong>R&eacute;alisation de la vente (facultatif)<\/strong><\/p>\n<p>\n\t\tEn cas d&rsquo;acceptation de l&rsquo;offre d&rsquo;achat, l&rsquo;acte authentique de la vente sera re&ccedil;u par Ma&icirc;tre _______________ <span style=\"color:#800080;\">(nom)<\/span>, notaire &agrave; _____________ <span style=\"color:#800080;\">(ville)<\/span>, &eacute;ventuellement avec la participation du notaire du propri&eacute;taire-vendeur dans un d&eacute;lai de _____________ semaines &agrave; compter du jour de l&rsquo;acceptation par le propri&eacute;taire.<\/p>\n<p>\n\t\t<strong>R&eacute;gime de la proposition d&rsquo;achat<\/strong><\/p>\n<p>\n\t\tJe\/Nous d&eacute;clare\/d&eacute;clarons avoir &eacute;t&eacute; inform&eacute;(s) des dispositions des dispositions protectrices de l&rsquo;acqu&eacute;reur immobilier <span style=\"color:#800080;\">(loi SRU du 13\/12\/2000)<\/span> :<\/p>\n<p>\n\t\t&#8211; instaurant un d&eacute;lai de 7 jours pour tout acte sous seing priv&eacute; ayant pour objet l&rsquo;acquisition d&rsquo;un immeuble &agrave; usage d&rsquo;habitation par un acqu&eacute;reur non professionnel ;<\/p>\n<p>\n\t\t&#8211; frappant de nullit&eacute; tout engagement unilat&eacute;ral souscrit en vue de l&rsquo;acquisition d&rsquo;un bien ou droit immobilier pour lequel il est exig&eacute; ou re&ccedil;u de celui qui s&rsquo;engage un versement quelles qu&rsquo;en soit la cause et la forme.<\/p>\n<p>\n\t\tEn cons&eacute;quence, la pr&eacute;sente proposition d&rsquo;achat n&rsquo;est pas soumise au d&eacute;lai de 7 jours en ce qu&rsquo;elle a exclusivement pour objet d&rsquo;inviter le propri&eacute;taire, si le prix propos&eacute; lui convient, &agrave; r&eacute;gulariser avec moi\/nous, au plus tard &agrave; la date indiqu&eacute;e si dessus, un avant-contrat <span style=\"color:#800080;\">(promesse synallagmatique de vente ou compromis)<\/span> qui constatera l&rsquo;&eacute;change des consentements, fixera l&rsquo;ensemble des conditions de la vente (financement, conditions suspensives&hellip;) et engagera r&eacute;ciproquement les deux parties &agrave; l&rsquo;issue du d&eacute;lai de 7 jours ci-avant &eacute;voqu&eacute;.<\/p>\n<p>\n\t\tBien que n&rsquo;entrainant aucun versement de ma\/notre part, je\/nous suis\/sommes conscient(s) de l&rsquo;obligation que je me cr&eacute;e\/nous nous cr&eacute;ons de r&eacute;gulariser un avant-contrat, en cas d&rsquo;accord du propri&eacute;taire dans le d&eacute;lai indiqu&eacute; ci-dessus, sous peine d&rsquo;&ecirc;tre redevable(s) de dommages et int&eacute;r&ecirc;t &agrave; son &eacute;gard.&nbsp;<\/p>\n<p>\n\t\t&nbsp;<\/p>\n<p>\n\t\tFait en ________ exemplaires (autant d&rsquo;exemplaires que de parties)<\/p>\n<p>\n\t\tA &nbsp;___________ <span style=\"color:#800080;\">(ville)<\/span>, le _________ <span style=\"color:#800080;\">(date)<\/span><\/p>\n<p>\n\t\t&nbsp;<\/p>\n<p>\n\t\t<strong>Le(s) proposant(s)<\/strong><\/p>\n<p>\n\t\tNom et pr&eacute;nom<\/p>\n<p>\n\t\t<strong>Signature<\/strong> pr&eacute;c&eacute;d&eacute;e de la mention &laquo; Lu et approuv&eacute;, Bon pour proposition au prix de &hellip; &raquo; (somme en toutes lettres)<span class=\"Apple-tab-span\" style=\"white-space:pre\"> <\/span><\/p>\n<p>\n\t\t&nbsp;<\/p>\n<p>\n\t\t<strong>Le vendeur<\/strong><\/p>\n<p>\n\t\tNom pr&eacute;nom<\/p>\n<p>\n\t\t<strong>Signature<\/strong> pr&eacute;c&eacute;d&eacute;e de la mention &laquo; Bon pour acceptation &raquo;<\/p>\n<p>\n\t\t&nbsp;<\/p>\n<p>\n\t\tEventuellement <span style=\"color:#800080;\">(&agrave; enlever si la vente est faite entre non professionnels)<\/span><\/p>\n<p>\n\t\tL&rsquo;agence immobili&egrave;re<\/p>\n<p>\n\t\t<strong>Signature<\/strong><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Vous souhaitez acheter l&rsquo;appartement de vos reves. Le prix propose par le vendeur ne vous convenant pas, vous souhaitez faire une offre d&rsquo;achat.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[95],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/posts\/11707"}],"collection":[{"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/comments?post=11707"}],"version-history":[{"count":7,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/posts\/11707\/revisions"}],"predecessor-version":[{"id":13528,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/posts\/11707\/revisions\/13528"}],"wp:attachment":[{"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/media?parent=11707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/categories?post=11707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/tags?post=11707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}