{"id":11911,"date":"2011-10-05T00:00:59","date_gmt":"2011-10-04T23:00:59","guid":{"rendered":"http:\/\/best-of-high-tech.com\/fr\/?p=11911"},"modified":"2011-10-05T00:00:59","modified_gmt":"2011-10-04T23:00:59","slug":"messages-pour-condoleances-modele-de-texte","status":"publish","type":"post","link":"https:\/\/best-of-high-tech.com\/fr\/messages-pour-condoleances-modele-de-texte\/","title":{"rendered":"messages pour condol\u00e9ances &#8211; mod\u00e8le de texte de condol\u00e9ances"},"content":{"rendered":"<p style=\"text-align: justify; \">\n\t<strong>Vous venez d&#39;apprendre une disparition et vous souhaitez envoyer vos condol&eacute;ances &agrave; la famille du d&eacute;funt. Voici plusieurs exemples&#8230;<\/strong><\/p>\n<blockquote style=\"text-align: justify; \"><p>\n\tC&#39;est avec une grande tristesse que j&#39;ai appris le d&eacute;c&egrave;s soudain de &#8230;<\/p>\n<p>\tEn ces moments difficiles je tenais &agrave; vous faire part de mes sinc&egrave;res condol&eacute;ances et &agrave; partager votre peine.<\/p>\n<p>\tBien &agrave; vous.&nbsp;<\/p>\n<p style=\"text-align: justify; \">\n\t\t&nbsp;<\/p>\n<hr \/>\n<p style=\"text-align: justify; \">\n\t\t&nbsp;<\/p>\n<p style=\"text-align: justify; \">\n\t\tAyant appris le deuil qui vous frappe&nbsp;avec la disparition de votre &eacute;poux, je vous prie de recevoir mes tr&egrave;s sinc&egrave;res condol&eacute;ances et l&#39;expression de ma profonde sympathie.<\/p>\n<p style=\"text-align: justify; \">\n\t\t&nbsp;<\/p>\n<hr \/>\n<p style=\"text-align: justify; \">\n\t\t&nbsp;<\/p>\n<p style=\"text-align: justify; \">\n\t\tLe Deuil inattendu qui vous frappe m&#39;&eacute;meut profond&eacute;ment.&nbsp;<br \/>\n\t\tJe voudrai pouvoir prendre une grande part &agrave; votre souffrance et all&eacute;ger, autant que possible, cette tr&egrave;s dure &eacute;preuve.&nbsp;<br \/>\n\t\tCroyez en toute mon amiti&eacute;.<\/p>\n<p style=\"text-align: justify; \">\n\t\t&nbsp;<\/p>\n<hr \/>\n<p style=\"text-align: justify; \">\n\t\t&nbsp;<\/p>\n<p style=\"text-align: justify; \">\n\t\tCatherine et moi vous pr&eacute;sentons toutes nos condol&eacute;ances pour le d&egrave;c&egrave;s de Gilles.<\/p>\n<p style=\"text-align: justify; \">\n\t\tJe vous demande de bien vouloir excuser mon absence aux obs&egrave;ques car j&#39;&eacute;tais aux Antilles.<br \/>\n\t\tBon courage en ces moments difficiles.<br \/>\n\t\tAmiti&egrave;s<br \/>\n\t\tjean-jacques martin<\/p>\n<p style=\"text-align: justify; \">\n\t\t&nbsp;<\/p>\n<hr \/>\n<p style=\"text-align: justify; \">\n\t\t&nbsp;<\/p>\n<p style=\"text-align: justify; \">\n\t\tD&eacute;c&egrave;s du p&egrave;re d&#39;un ami<\/p>\n<p style=\"text-align: justify; \">\n\t\t&quot;Aussi grande que soit ta souffrance et ta peine aujourd&#39;hui, sois assur&eacute; que notre amiti&eacute; t&#39;apportera le soutien et le r&eacute;confort pour traverser cette &eacute;preuve dans le temps&quot;<br \/>\n\t\tTes amis<br \/>\n\t\t&nbsp;<\/p>\n<\/blockquote>\n<p style=\"text-align: justify; \">\n\t<em><strong>Bon &agrave; savoir :<\/strong><\/em><\/p>\n<p style=\"text-align: justify; \">\n\t<em>Les condol&eacute;ances sont &agrave; r&eacute;diger &agrave; la main et peuvent &ecirc;tre &eacute;crites sur une carte de correspondance.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vous venez d&rsquo;apprendre une disparition et vous souhaitez envoyer vos condol\u00e9ances \u00e0 la famille du d\u00e9funt. Voici plusieurs exemples&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[96],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/posts\/11911"}],"collection":[{"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/comments?post=11911"}],"version-history":[{"count":14,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/posts\/11911\/revisions"}],"predecessor-version":[{"id":13497,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/posts\/11911\/revisions\/13497"}],"wp:attachment":[{"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/media?parent=11911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/categories?post=11911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/tags?post=11911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}