{"id":1413,"date":"2009-10-16T21:15:25","date_gmt":"2009-10-16T20:15:25","guid":{"rendered":"http:\/\/best-of-high-tech.com\/fr\/?p=1413"},"modified":"2009-11-11T01:22:52","modified_gmt":"2009-11-11T00:22:52","slug":"presentation-samsung-s7350","status":"publish","type":"post","link":"https:\/\/best-of-high-tech.com\/fr\/presentation-samsung-s7350\/","title":{"rendered":"samsung S7350 : presentation et un test en video du mobile"},"content":{"rendered":"<p style=\"text-align: justify;\">\n\tLe S7350 est un t&eacute;l&eacute;phone mobile 3G+ dot&eacute; d&#39;un &eacute;cran non tactile 2,6 pouces (240 x 400 pixels) capable d&#39;afficher 16,7 millions de couleurs. cet appaireil dispose d&rsquo;un appareil photo 5 millions de pixels qui offre de nombreuses fonctionnalit&eacute;s avanc&eacute;es : autofocus, mode panorama ou mode portrait comprenant la d&eacute;tection de sourires, flash Power Led, zoom num&eacute;rique 4x&#8230; Multim&eacute;dia complet, ce mobile est &eacute;galement un lecteur-enregistreur vid&eacute;o qui accepte les formats MPEG4, 3gp et DivX.&nbsp;<\/p>\n<p style=\"text-align: justify;\">\n\tCon&ccedil;u pour le haut d&eacute;bit 3G+ (HSDPA, 7.2Mbps) et compatible avec la technologie sans fil Bluetooth&trade; st&eacute;r&eacute;o, il permet de recevoir instantan&eacute;ment ses emails, de naviguer confortablement sur Internet et de t&eacute;l&eacute;charger des fichiers (photos, vid&eacute;os, MP3, documents Word, Excel, Powerpoint et PDF). Avec sa m&eacute;moire interne de 100 Mo ainsi que son port MicroSD, il vous sera facile de stocker l&rsquo;ensemble de vos documents.&nbsp;<\/p>\n<p style=\"text-align: justify;\">\n\t<br \/>\n\tLe mobile se transforme &eacute;galement en v&eacute;ritable jukebox et permet d&rsquo;&eacute;couter des heures de musique &agrave; partir de sa radio FM avec syst&egrave;me RDS mais aussi de son lecteur MP3, AAC, AAC+, AMR et WMA. Il b&eacute;n&eacute;ficie des derni&egrave;res technologies telles que la reconnaissance musicale et le DNSe (Digital Natural Sound engine) qui d&eacute;livre un son net et puissant pour un plaisir d&rsquo;&eacute;coute intense.<\/p>\n<p>\n\t<br \/>\n\tPermettant le g&eacute;totagging, la g&eacute;olocalisation et la navigation avec Google Maps, le SAMSUNG Player Ultra devient un v&eacute;ritable guide lors des d&eacute;placements.<\/p>\n<p>\n\t<img loading=\"lazy\" decoding=\"async\" align=\"left\" alt=\"samsung-s7350\" class=\"alignleft size-full wp-image-1416\" height=\"252\" hspace=\"20\" src=\"http:\/\/best-of-high-tech.com\/fr\/wp-content\/uploads\/2009\/10\/samsung-s7350.jpg\" title=\"samsung-s7350\" width=\"122\" srcset=\"https:\/\/best-of-high-tech.com\/fr\/wp-content\/uploads\/2009\/10\/samsung-s7350.jpg 218w, https:\/\/best-of-high-tech.com\/fr\/wp-content\/uploads\/2009\/10\/samsung-s7350-145x300.jpg 145w\" sizes=\"(max-width: 122px) 100vw, 122px\" \/><\/p>\n<p>\n\t&nbsp;<\/p>\n<p>\n\t<span style=\"font-size: small;\"><strong>les points forts :<\/strong><\/span><\/p>\n<p>\n\t&nbsp;&nbsp; &#8211;&nbsp; Le g&eacute;otagging<\/p>\n<p>\n\t&nbsp;&nbsp; &#8211;&nbsp; APN de 5 m&eacute;gapixels<\/p>\n<p>\n\t<strong><span style=\"font-size: small;\">les points faible&nbsp; :<\/span><\/strong><\/p>\n<p>\n\t&nbsp; &nbsp; &#8211; &nbsp; autonomie de seulement 4 heures en communications<\/p>\n<p>\n\t&nbsp;<\/p>\n<p>\n\t&nbsp;<\/p>\n<p>\n\t&nbsp;<\/p>\n<p>\n\t&nbsp;<\/p>\n<p>\n\t&nbsp;<span style=\"font-size: small;\"><strong>Une vid&eacute;o de test et de&nbsp; pr&eacute;sentation de l&#39;interface et de quelques options tel que les sonneries :<\/strong><\/span><\/p>\n<p>\n\t<object height=\"344\" width=\"425\"><param name=\"movie\" value=\"http:\/\/www.youtube.com\/v\/DuNY9bKi1Ao&amp;color1=0xb1b1b1&amp;color2=0xcfcfcf&amp;feature=player_embedded&amp;fs=1\" \/><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowScriptAccess\" value=\"always\" \/><embed allowfullscreen=\"true\" allowscriptaccess=\"always\" height=\"344\" src=\"http:\/\/www.youtube.com\/v\/DuNY9bKi1Ao&amp;color1=0xb1b1b1&amp;color2=0xcfcfcf&amp;feature=player_embedded&amp;fs=1\" type=\"application\/x-shockwave-flash\" width=\"425\"><\/embed><\/object><\/p>\n","protected":false},"excerpt":{"rendered":"<p>tous les caract\u00e9ristiques techniques du  samsung s7350 et un test en vid\u00e9o avec pr\u00e9sentation de l&rsquo;interface et de differentes options.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[5,17],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/posts\/1413"}],"collection":[{"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/comments?post=1413"}],"version-history":[{"count":27,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/posts\/1413\/revisions"}],"predecessor-version":[{"id":2620,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/posts\/1413\/revisions\/2620"}],"wp:attachment":[{"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/media?parent=1413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/categories?post=1413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/tags?post=1413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}