{"id":9968,"date":"2011-07-11T17:39:52","date_gmt":"2011-07-11T16:39:52","guid":{"rendered":"http:\/\/best-of-high-tech.com\/fr\/?p=9968"},"modified":"2011-07-11T17:39:52","modified_gmt":"2011-07-11T16:39:52","slug":"modele-de-lettre-de-motivation-vendeuse-hotesse-de-caisse-exemple-gratuit","status":"publish","type":"post","link":"https:\/\/best-of-high-tech.com\/fr\/modele-de-lettre-de-motivation-vendeuse-hotesse-de-caisse-exemple-gratuit\/","title":{"rendered":"modele de lettre de motivation vendeuse &#8211; h\u00f4tesse de caisse &#8211; exemple gratuit"},"content":{"rendered":"<p style=\"text-align: justify; \">\n\t<strong>Un exemple de lettre de motivation pour une candidature spontan&eacute;e pour un poste de vendeuse &#8211; h&ocirc;tesse de caisse&nbsp;&nbsp; :<\/strong><\/p>\n<p style=\"margin-left: 40px; \">\n\t<span style=\"font-size: 14px; \"><strong>Votre Pr&eacute;nom NOM<\/strong><\/span><br \/>\n\tVotre adresse compl&egrave;te<br \/>\n\tT&eacute;l&eacute;phone \/ Email&#8230;<\/p>\n<p style=\"margin-left: 360px; \">\n\t<strong><span style=\"font-size: 14px; \">NOM DE LA SOCIETE<\/span><\/strong><br \/>\n\tAdresse de la soci&eacute;t&eacute;<\/p>\n<p style=\"margin-left: 360px; \">\n\tParis, le Jeudi 16 Juin 2011<\/p>\n<p style=\"margin-left: 200px; \">\n\t<strong>Madame, Monsieur,<\/strong><\/p>\n<p style=\"margin-left: 200px; \">\n\t&nbsp;<\/p>\n<p style=\"text-align: justify; margin-left: 40px; \">\n\tPr&eacute;parant actuellement un Master de Biologie, je suis &agrave; la recherche d&#39;un contrat &eacute;tudiant &agrave; temps partiel.<\/p>\n<p style=\"text-align: justify; margin-left: 40px; \">\n\tUne activit&eacute; professionnelle dans le domaine du commerce me permettrait de compl&eacute;ter mon cursus universitaire. Dynamique, motiv&eacute;e, et polyvalente, je pense avoir les qualit&eacute;s requises pour int&eacute;grer une de vos &eacute;quipes. Je suis &agrave; votre disposition pour vous exposer mes motivations de vive voix au cours d&#39;un entretien.<\/p>\n<p style=\"text-align: justify; margin-left: 40px; \">\n\tEsp&eacute;rant que vous r&eacute;pondrez favorablement &agrave; ma demande, je vous prie d&#39;agr&eacute;er, Madame, Monsieur, l&#39;expression de mes salutations distingu&eacute;es.<\/p>\n<p style=\"text-align: justify; margin-left: 520px; \">\n\t<span class=\"Apple-style-span\" style=\"font-weight: bold; \">Ma Signature<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un exemple de lettre de motivation pour une candidature spontan\u00e9e pour un poste de vendeuse &#8211; h\u00f4tesse de caisse   :<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[93],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/posts\/9968"}],"collection":[{"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/comments?post=9968"}],"version-history":[{"count":4,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/posts\/9968\/revisions"}],"predecessor-version":[{"id":10480,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/posts\/9968\/revisions\/10480"}],"wp:attachment":[{"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/media?parent=9968"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/categories?post=9968"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/tags?post=9968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}