{"id":9972,"date":"2011-07-11T17:39:40","date_gmt":"2011-07-11T16:39:40","guid":{"rendered":"http:\/\/best-of-high-tech.com\/fr\/?p=9972"},"modified":"2011-07-11T17:39:40","modified_gmt":"2011-07-11T16:39:40","slug":"modele-lettre-motivation-charge-etude-qualite","status":"publish","type":"post","link":"https:\/\/best-of-high-tech.com\/fr\/modele-lettre-motivation-charge-etude-qualite\/","title":{"rendered":"modele de lettre de motivation charg\u00e9 d&rsquo;etude qualit\u00e9 &#8211; organisation"},"content":{"rendered":"<p style=\"text-align: justify; \">\n\t<strong>Un exemple de lettre de motivation pour une candidature spontan&eacute;e pour un poste de charg&eacute; d&#39;etude qualit&eacute; &#8211; organisation &nbsp; :<\/strong><\/p>\n<p style=\"margin-left: 40px; \">\n\t<span style=\"font-size: 14px; \"><strong>Votre Pr&eacute;nom NOM<\/strong><\/span><br \/>\n\tVotre adresse compl&egrave;te<br \/>\n\tT&eacute;l&eacute;phone \/ Email&#8230;<\/p>\n<p style=\"margin-left: 360px; \">\n\t<strong><span style=\"font-size: 14px; \">NOM DE LA SOCIETE<\/span><\/strong><br \/>\n\tAdresse de la soci&eacute;t&eacute;<\/p>\n<p style=\"margin-left: 360px; \">\n\tParis, le Jeudi 16 Juin 2011<\/p>\n<p style=\"margin-left: 200px; \">\n\t<strong>Madame, Monsieur,<\/strong><\/p>\n<div>\n\t<strong><br \/>\n\t<\/strong><\/div>\n<p style=\"text-align: justify; margin-left: 40px; \">\n\tDipl&ocirc;m&eacute; de l&#39;Ecole Sup&eacute;rieure de Commerce XXXX (sp&eacute;cialit&eacute; management des syst&egrave;mes d&#39;information), je sollicite par la pr&eacute;sente une place au sein de votre entreprise en tant que Charg&eacute; d&#39;&eacute;tudes organisation\/qualit&eacute;.<\/p>\n<p style=\"text-align: justify; margin-left: 40px; \">\n\tLes missions qui m&#39;ont &eacute;t&eacute; confi&eacute;es, tant au cours de ma formation qu&#39;au travers de mon exp&eacute;rience professionnelle, m&#39;ont donn&eacute; l&#39;occasion d&#39;acqu&eacute;rir de solides connaissances en gestion de projet et en organisation (notamment lors de la mise en place d&#39;un syst&egrave;me de management de la qualit&eacute; au sein du r&eacute;seau XXXX : cartographie et optimisation des processus) ; mais cela m&#39;a aussi permis d&#39;apprendre &agrave; m&#39;int&eacute;grer de fa&ccedil;on rapide et efficace au sein d&#39;&eacute;quipes pluridisciplinaires et d&#39;&eacute;voluer dans des environnements en perp&eacute;tuelle expansion.<\/p>\n<p style=\"text-align: justify; margin-left: 40px; \">\n\tParlant couramment l&#39;anglais et l&#39;allemand, disposant d&#39;un tr&egrave;s bon sens relationnel, je suis d&eacute;sireux de m&#39;investir dans de nouvelles missions li&eacute;es &agrave; la qualit&eacute;\/organisation et &agrave; la conduite du changement. C&#39;est pourquoi je me propose de mettre &agrave; votre disposition mon sens de l&#39;organisation, mon esprit d&#39;initiative et ma capacit&eacute; &agrave; travailler en &eacute;quipe.<\/p>\n<p style=\"text-align: justify; margin-left: 40px; \">\n\tJe serais heureux de vous exposer mes motivations et mes acquis professionnels, mais aussi de vous convaincre de l&#39;int&eacute;r&ecirc;t de ma collaboration au cours d&#39;un entretien.<\/p>\n<p style=\"text-align: justify; margin-left: 40px; \">\n\tDans l&#39;attente de vous rencontrer pour vous donner de plus amples informations, je vous prie de croire, Madame, Monsieur, &agrave; l&#39;assurance de mes salutations distingu&eacute;es.<\/p>\n<p style=\"text-align: justify; margin-left: 520px; \">\n\t<span class=\"Apple-style-span\" style=\"font-weight: bold; \">Ma Signature<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un exemple de lettre de motivation pour une candidature spontan\u00e9e pour un poste de charg\u00e9 d&rsquo;etude qualit\u00e9 &#8211; organisation   :<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[93],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/posts\/9972"}],"collection":[{"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/comments?post=9972"}],"version-history":[{"count":3,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/posts\/9972\/revisions"}],"predecessor-version":[{"id":10479,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/posts\/9972\/revisions\/10479"}],"wp:attachment":[{"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/media?parent=9972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/categories?post=9972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/best-of-high-tech.com\/fr\/wp-json\/wp\/v2\/tags?post=9972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}